{"id":3687,"date":"2021-11-17T13:43:23","date_gmt":"2021-11-17T12:43:23","guid":{"rendered":"https:\/\/niunapalabraanadie.com\/pineda\/escuela-verde\/"},"modified":"2024-12-12T13:26:36","modified_gmt":"2024-12-12T12:26:36","slug":"escuela-verde","status":"publish","type":"page","link":"https:\/\/pineda.es\/es\/escuela-verde\/","title":{"rendered":"Escuela verde"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3687\" class=\"elementor elementor-3687 elementor-1550\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7b8aced elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7b8aced\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12b2130\" data-id=\"12b2130\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7de9915 elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"7de9915\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-8bc8c26 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">ESCUELA VERDE<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d54c3eb elementor-widget elementor-widget-spacer\" data-id=\"d54c3eb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed76017 elementor-widget elementor-widget-spacer\" data-id=\"ed76017\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e68acd4 elementor-widget elementor-widget-image\" data-id=\"e68acd4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2022\/02\/Logo-escola-verda-1-1024x576.jpg\" class=\"attachment-large size-large wp-image-7624\" alt=\"\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2022\/02\/Logo-escola-verda-1-1024x576.jpg 1024w, https:\/\/pineda.es\/wp-content\/uploads\/2022\/02\/Logo-escola-verda-1-300x169.jpg 300w, https:\/\/pineda.es\/wp-content\/uploads\/2022\/02\/Logo-escola-verda-1-768x432.jpg 768w, https:\/\/pineda.es\/wp-content\/uploads\/2022\/02\/Logo-escola-verda-1-1536x864.jpg 1536w, https:\/\/pineda.es\/wp-content\/uploads\/2022\/02\/Logo-escola-verda-1.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-87899ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87899ec\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b22fb69\" data-id=\"b22fb69\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b1b4c7 elementor-widget elementor-widget-heading\" data-id=\"1b1b4c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aprender a vivir de manera sostenible. Buscar alternativas y soluciones pr\u00e1cticas para tener cuidado del planeta.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed063e6 elementor-widget elementor-widget-text-editor\" data-id=\"ed063e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a (XESC) y, como tal, a\u00f1o tras a\u00f1o implementamos nuevas medidas -que afectan tanto a acciones espor\u00e1dicas como a comportamientos habituales- que pretenden hacer de la sostenibilidad una forma de vivir y de funcionar a nivel personal y como escuela, ahora y en el futuro.<\/p><p>El proyecto de Escola Verda est\u00e1 liderado por un CONSEJO VERDE formado por:<\/p><ul><li>Voluntarias Ambientales: alumnos voluntarias desde 5\u00ba de Primaria hasta 2\u00ba de Bachillerato.<\/li><li>Comisi\u00f3n Verde: profesoras voluntarias de Primaria y Secundaria.<\/li><li>Personal no docente<\/li><\/ul><p>\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28c8410 elementor-widget elementor-widget-heading\" data-id=\"28c8410\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es Escola Verda?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f05b12 elementor-widget elementor-widget-text-editor\" data-id=\"6f05b12\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Durante el curso 2015-16 en Pineda se empez\u00f3 el Proyecto Escola Verda para poder formar parte de la Red de Escuelas para la Sostenibilidad de Catalu\u00f1a (XESC) y obtener el distintivo de Escola Verda.<\/p>\n<p>El programa Escola Verda, con m\u00e1s de 15 a\u00f1os de bagaje y m\u00e1s de 500 escuelas que forman parte, surge como un compromiso para apoyar a todos los centros educativos de Catalu\u00f1a que quieren innovar, incluir, avanzar, sistematizar y organizar acciones educativas que tengan la finalidad de afrontar, desde la educaci\u00f3n, los nuevos retos y valores de la sostenibilidad.<\/p>\n<p>\u00bfY qu\u00e9 significa sostenibilidad? Descrito en 1987 por la Comisi\u00f3n Mundial para el Medio Ambiente y Desarrollo de Naciones Unidas, el desarrollo sostenible es aquella forma de desarrollo que satisface las necesidades de las generaciones presentes sin comprometer la posibilidad de las generaciones futuras de satisfacer sus necesidades. Actualmente, se habla en sentido gen\u00e9rico de Sostenibilidad, incluyendo de este modo todas las actividades humanas (acciones, decisiones, comportamientos, tecnolog\u00edas, etc.) que velan para conseguir este objetivo de proveer lo mejor para las personas y el medio ambiente, ahora y en el futuro indefinidamente.<\/p>\n<p>Contextualizada en el momento actual que estamos viviendo, de evidencias sobre el cambio clim\u00e1tico, extinci\u00f3n de especies a ritmo trepidante, pobreza energ\u00e9tica, desperdicio de alimentos\u2026 El Papa Francisco ha escrito la enc\u00edclica Laudato si (2015) en la que hace una llamada a todos los cristianos del mundo a ser conscientes de estos problemas ya ponerle remedio, ya que la tierra es \u201cla casa de todos\u201d y nosotros somos jardineros.<\/p>\n<p>Es por todos estos motivos que en Pineda hemos decidido que no podemos quedarnos de brazos cruzados y que debemos empezar actuar de forma diferente, desde la escuela y hacia las familias.<\/p>\n<p>\u00a1Necesitamos vuestra colaboraci\u00f3n!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb201a elementor-widget elementor-widget-heading\" data-id=\"6cb201a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Objetivos<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3632e1 elementor-widget elementor-widget-toggle\" data-id=\"f3632e1\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2551\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2551\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Curso 2015 - 2016<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2551\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2551\"><p>Creaci\u00f3n del Consell Verd, el \u00f3rgano de participaci\u00f3n del proyecto Escola Verda donde participan alumnos, profesoras y personal no docente. <span style=\"color: #99cc00;\">OBJETIVO ALCANZADO<\/span><\/p>\n<p>Incluir la sostenibilidad en el Proyecto Educativo de Centro. <span style=\"color: #99cc00;\">OBJETIVO ALCANZADO<\/span><\/p>\n<p>Incluir el proyecto Escuela Verde en el web de la escuela. <span style=\"color: #ff9900;\">OBJETIVO NO ALCANZADO<\/span><\/p>\n<p>Realizar la recogida de papel en todo el centro educativo. <span style=\"color: #99cc00;\">OBJETIVO ALCANZADO<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2552\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2552\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Curso 2016 - 2017<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2552\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2552\"><p>Incorporar a la web de la escuela el proyecto Escola Verda. <span style=\"color: #ff9900;\">OBJETIVO NO ALCANZADO<\/span><\/p>\n<p>Consolidar el Consell Verd, el \u00f3rgano de participaci\u00f3n del proyecto Escola Verda donde participan alumnos, profesoras y personal no docente. <span style=\"color: #99cc00;\">OBJETIVO ALCANZADO (Hay que mejorar)<\/span><\/p>\n<p>Continuar con la recogida selectiva de papel en todo el centro educativo. <span style=\"color: #99cc00;\">OBJETIVO ALCANZADO. (Ahora a reducir)<\/span><\/p>\n<p>Implementar un plan de mejora de la movilidad de toda la comunidad educativa. <span style=\"color: #99cc00;\">ESTAMOS TRABAJANDO<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2553\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2553\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Curso 2017 - 2018<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2553\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2553\"><p>Dinamizar la Comisi\u00f3n Verde e implicar m\u00e1s a toda la comunidad educativa en el proyecto Escola Verda.<span style=\"color: #ff9900;\"> OBJETIVO NO ALCANZADO<\/span><\/p>\n<p>Incorporar a la web de la escuela el Proyecto de Escola Verda <span style=\"color: #99cc00;\">OBJETIVO ALCANZADO<\/span><\/p>\n<p>Continuar con la recogida selectiva de papel en todo el centro educativo. <span style=\"color: #99cc00;\">OBJETIVO ALCANZADO (Continuamos el pr\u00f3ximo curso)<\/span><\/p>\n<p>Fomentar la reducci\u00f3n y reutilizaci\u00f3n de papel. <span style=\"color: #99cc00;\">OBJETIVO ALCANZADO (Continuamos el pr\u00f3ximo curso)<\/span><\/p>\n<p>Proyecto Patis Nets (reducci\u00f3n y reciclaje de residuos del desayuno y mejora de la limpieza de los patios) <span style=\"color: #99cc00;\">AUN ESTAMOS TRABAJANDO<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2554\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2554\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Curso 2018 - 2019<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2554\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2554\"><p>Durante el <strong>PRIMER TRIMESTRE<\/strong> realizamos todas estas actividades:<\/p>\n<ol>\n<li>Hemos creado nuestro Comit\u00e9 Ambiental de Primaria y ESO.<\/li>\n<li>\u00a1Las de la Comisi\u00f3n Verde de Primaria han creado RECIARRO!<\/li>\n<\/ol>\n<p> <img decoding=\"async\" class=\"alignnone size-medium wp-image-2371\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG_20181127_104927-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG_20181127_104927-225x300.jpg 225w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG_20181127_104927.jpg 240w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>.  <img decoding=\"async\" class=\"alignnone size-medium wp-image-2372\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG_20181127_104916-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG_20181127_104916-225x300.jpg 225w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG_20181127_104916.jpg 240w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>  3. LLas alumnas de la E<strong>SO participaron en el IV FORO XESC del Baix LLobregat Secundaria.<\/strong> Explicaron su Proyecto \u201cpatios limpios con el recicarro\u201d y disfrutaron de otros proyectos realizados en diferentes escuelas presentados por otros alumnos. Las profesoras formaron parte de un grupo de trabajo para formular estrategias para futuras acciones en el colegio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2373\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG-0027-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG-0027-300x225.jpg 300w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG-0027.jpg 320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2374\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG-0035-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG-0035-300x225.jpg 300w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG-0035.jpg 320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <\/p>\n<p>Adem\u00e1s, siempre buscan tiempos para llenar las paredes con noticias relacionadas con Escola Verda y acciones que podemos hacer para crear un planeta m\u00e1s limpio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095294\/objectius\/curs-2018-2019\/escola%20verda%20eso.jpg?height=299&amp;width=400\" width=\"400\" height=\"299\" border=\"0\"> <\/p>\n<p>4. Avantis tambi\u00e9n apuesta por ESCUELA Verde y empieza a realizar peque\u00f1as acciones. \u00a1Una de ellas el <strong>reciclaje de papel!<\/strong><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095086\/objectius\/curs-2018-2019\/Inf.jpg?height=320&amp;width=240\" width=\"240\" height=\"320\" border=\"0\">    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095295\/objectius\/curs-2018-2019\/infaa.jpg?height=400&amp;width=300\" alt=\"\u00a1Mirad qu\u00e9 han hecho los ni\u00f1os! Han preparado papeleras para reciclar el papel en todas las aulas.\" width=\"300\" height=\"400\" border=\"0\"><\/strong><\/p>\n<\/p>\n<p>Este<strong>SEGUNDO TRIMESTRE<\/strong> hemos empezado con el concurso APILO XXII !!<\/p>\n<p>Las alumnas de primaria han pasado a explicar por otros cursos en qu\u00e9 consiste el CONCURSO y qu\u00e9 debemos hacer para cuidar nuestro entorno.<br \/>\u00a1Han repartido una caja de pilas que cuando est\u00e9 llena la podr\u00e1n vaciar en el recipiente que est\u00e1 en Recepci\u00f3n!<\/p>\n<p>Vea que llenos est\u00e1n!!!! \u00a1Ahora por el cuarto bid\u00f3n!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095085\/objectius\/curs-2018-2019\/IMG_20190131_155033.jpg?height=200&amp;width=150\" width=\"150\" height=\"200\" border=\"0\">  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095084\/objectius\/curs-2018-2019\/IMG_20190131_155029.jpg?height=200&amp;width=150\" width=\"150\" height=\"200\" border=\"0\">  <img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095085\/objectius\/curs-2018-2019\/IMG_20190311_175216.jpg?height=150&amp;width=200\" width=\"250\" height=\"188\" border=\"0\"><\/p>\n<p>Las <strong>alumnas de quinto y sexto de primaria<\/strong> salieron de las clases y quisieron explicar el cuento de APilo XII a las alumnas de ciclo inicial. Se lo pasaron a las mil maravillas!!!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095084\/objectius\/curs-2018-2019\/IMG-20190220-WA0007.jpg?height=300&amp;width=400\" width=\"344\" height=\"258\" border=\"0\">    <img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095294\/objectius\/curs-2018-2019\/PLANE.png\" width=\"511\" height=\"234\" border=\"0\"><\/p>\n<p>El el pasado jueves <strong>tres alumnos de ciclo superior<\/strong> participaron al Foro del Vall\u00e8s Occidental de primaria! Este a\u00f1o ten\u00eda como tem\u00e1tica <strong>Pl\u00e1stico Cero en las escuelas.<\/strong><\/p>\n<p>Aqu\u00ed os dejamos la notic\u00eda que han creado nuestras alumnas de sexto: la Mar\u00eda Oliveras, Laia Cabello y la Clara Su\u00e1rez. Felicidades!!!!<\/p>\n<p> <img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095294\/objectius\/curs-2018-2019\/f%C3%B2rum%20definitu_page-0001.jpg\" width=\"368\" height=\"521\" border=\"0\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095084\/objectius\/curs-2018-2019\/IMG-20190328-WA0006.jpg?height=300&amp;width=400\" width=\"504\" height=\"378\" border=\"0\"><\/p>\n<\/p>\n<p>Hemos acabado el curso con la <strong>JORNADA De ESCUELA VERDE!!!!<\/strong><\/p>\n<p>Las alumnas de primaria han construido un RECICLAJOC con materiales reutilizados y han salido al pat\u00edn a jugar con ellos!<\/p>\n<p>Mirad que bien se lo han pasado!!!!!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095085\/objectius\/curs-2018-2019\/IMG_20190618_154847.jpg?height=240&amp;width=320\" width=\"320\" height=\"240\" border=\"0\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095085\/objectius\/curs-2018-2019\/IMG_20190618_162759.jpg?height=240&amp;width=320\" width=\"320\" height=\"240\" border=\"0\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095085\/objectius\/curs-2018-2019\/IMG_20190618_160454%20%281%29.jpg?height=240&amp;width=320\" width=\"320\" height=\"240\" border=\"0\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095085\/objectius\/curs-2018-2019\/IMG_20190618_161734.jpg?height=240&amp;width=320\" width=\"320\" height=\"240\" border=\"0\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095085\/objectius\/curs-2018-2019\/IMG_20190618_160005.jpg?height=320&amp;width=157\" width=\"157\" height=\"320\" border=\"0\"><\/p>\n<p>Un grupo de alumnas voluntarias de la ESO nos hicieron ZUMBA con <strong>el Himno de ESCUELA VERDE<\/strong> que se inventaron las alumnas de Ciclo Superior.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095085\/objectius\/curs-2018-2019\/IMG_20190619_161357.jpg?height=240&amp;width=320\" width=\"320\" height=\"240\" border=\"0\">.  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.google.com\/a\/pineda.es\/escolaverda\/_\/rsrc\/1612867095085\/objectius\/curs-2018-2019\/IMG_20190619_161815.jpg?height=240&amp;width=320\" width=\"320\" height=\"240\" border=\"0\"><\/p><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2555\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2555\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Curso 2019 - 2020<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2555\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2555\"><p>Pineda es <span style=\"color: #99cc00;\">ESCUELA VERDE<\/span><\/p>\n<p>Todo el mundo queremos mejorar nuestro entorno natural, pero a veces no sabemos qu\u00e9 hacer.<\/p>\n<p>En la escuela tenemos un solo objetivo para este curso: ambicioso, pero realista si nos ponemos: <span style=\"color: #99cc00;\">Cero papel de aluminio<\/span><\/p>\n<p>Producir aluminio supone un gasto energ\u00e9tico muy elevada por eso tenemos que procurar no hacer un uso innecesario.<\/p>\n<p>Para conseguir este objetivo os animamos a no usar papel de aluminio para envolver el almuerzo; llev\u00e1is fiambreras de pl\u00e1stico que no sea desechable, boc&amp;rols, papel de cocina, la misma bolsa del pan&#8230;<\/p>\n<p>\u00bfCu\u00e1nto papel de aluminio ahorrar\u00edamos si lo dej\u00e1ramos de usar para envolver los bocadillos?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2370\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG-20200215-WA0002-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG-20200215-WA0002-225x300.jpg 225w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/IMG-20200215-WA0002.jpg 768w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2556\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2556\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Curso 2020 - 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2556\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2556\"><p>Necesitamos vuestra colaboraci\u00f3n!<\/p><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d01c3c7 elementor-widget elementor-widget-spacer\" data-id=\"d01c3c7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d508dfb elementor-widget elementor-widget-heading\" data-id=\"d508dfb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Distintivo Escuela Verde<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a6df53 elementor-widget elementor-widget-text-editor\" data-id=\"9a6df53\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Despu\u00e9s de hacer una diagnosis ambiental de la situaci\u00f3n de partida de Pineda, la Comisi\u00f3n Verde ha redactado unos objetivos estrat\u00e9gicos relacionados con la Educaci\u00f3n por la Sostenibilidad para llevar a cabo durante los 8 a\u00f1os siguientes y ordenados seg\u00fan su prioridad. Seg\u00fan estas prioridades, cada a\u00f1o el Consejo Verde define los objetivos para el curso escolar en un Plan de acci\u00f3n.<\/p><p>El reconocimiento que el centro forma parte de la Red de Escuelas Verdes se realiza, por primera vez, despu\u00e9s de haber ejecutado satisfactoriamente el primer Plan de acci\u00f3n de centro.<\/p><p>Cada 4 a\u00f1os, el centro lleva a cabo una autoevaluaci\u00f3n global que implica una revisi\u00f3n del Plan de Educaci\u00f3n para la Sostenibilidad.<\/p><p>Cada 8 a\u00f1os, el centro actualiza su Plan de educaci\u00f3n para la sostenibilidad. Es decir, hace una autoevaluaci\u00f3n global m\u00e1s profunda, que implica una nueva diagnosis de la situaci\u00f3n en que se encuentra el centro, identifica los nuevos objetivos estrat\u00e9gicos que hay que lograr y hace una nueva priorizaci\u00f3n de estos objetivos.<\/p><p>El pasado 23 de septiembre de 2017, la Generalitat de Catalu\u00f1a otorg\u00f3 en nuestra escuela el distintivo ESCUELA VERDE.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d08b680 elementor-widget elementor-widget-image\" data-id=\"d08b680\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"480\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.03.50-1024x614.png\" class=\"attachment-large size-large wp-image-3401\" alt=\"\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.03.50-1024x614.png 1024w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.03.50-300x180.png 300w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.03.50-768x461.png 768w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.03.50-1536x922.png 1536w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.03.50-2048x1229.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4df1d30 elementor-widget elementor-widget-spacer\" data-id=\"4df1d30\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-822fdaa elementor-widget elementor-widget-heading\" data-id=\"822fdaa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Experiencias<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22de207 elementor-widget elementor-widget-toggle\" data-id=\"22de207\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3651\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3651\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Hemos instalado placas solares<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3651\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3651\"><p>En el Centro Cultural Pineda, para la instalaci\u00f3n de la Escuela Pineda, siempre tenemos presente la importancia del Medio Ambiente, tanto para la sociedad como para nuestras actividades. Por eso, en nuestro compromiso por reducir el impacto ambiental, se ha hecho una inversi\u00f3n mediante la instalaci\u00f3n de placas solares sobre cubierta, cosa que nos permite generar energ\u00eda limpia, renovable y sostenible.<\/p><p>El Centro Cultural Pineda ha invertido en esta instalaci\u00f3n un total de 101.573,73 \u20ac, en 162 paneles solares con una potencia unitaria de 440 Wp, siendo la potencia total instalada de 71,28 kWp y estimando una producci\u00f3n anual de 83.444 kWh\/a\u00f1o.<\/p><p>Esta inversi\u00f3n se ha llevado a cabo gracias a las ayudas del Programa de incentivos ligados al autoconsumo y el almacenamiento, con fuentes de energ\u00eda renovables, en el marco del Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia, financiado por la Uni\u00f3n Europea \u2013 NextGeneartionEU, obteniendo una ayuda de 16.216,20 \u20ac.<\/p><p style=\"text-align: right;\"><em>Expediente ICA025\/21\/061009<\/em><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3652\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-3652\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Jornada Escuela Verde 2018<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3652\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-3652\"><p>El pasado 20 de junio por la tarde, todo primaria y secundaria celebramos la Jornada de Escuela Verde con muchas actividades y talleres, desde observar los animales microsc\u00f3picos del patio, hacer boc&#8217;n&#8217;rolls a un mercado de intercambio. Nos lo pasamos muy bien! Gracias a todas las alumnas y profesoras para hacerlo posible!<\/p>\n<p>Pod\u00e9is ver las fotos a las noticias de la escuela:<br \/>http:\/\/www.pineda.es\/actualitat\/celebrem-la-ii-jornada-d-escola-verda#<\/p>\n<p>Muy buen verano a todos y todas!<\/p>\n<p>Os dejamos con los enlaces que proyectamos a secundaria por si quer\u00e9is seguir trabajando este verano:<br \/>https:\/\/www.youtube.com\/watch?v=_6xlNyWPpB8<\/p>\n<p><iframe title=\"Boyan Slat, el joven creador de &#039;The Ocean  Cleanup&#039; y su sue\u00f1o de limpiar los oc\u00e9anos\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/VeQZ81D8s5o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe title=\"The Ocean Cleanup - Launching in 2018\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/PePvbhy-qGY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe title=\"Plastic Planet\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/73sGgmZoMBQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe title=\"Cap 2 Objectiu #Rezero - Fam\u00edlia amb nens: &quot;Padre, he vuelto a pecar&quot;\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/EaS3K1-VLC0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe title=\"Midway, a plastic island\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/lsJqMmuFWO4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3653\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-3653\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">A recoger pilas usadas<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3653\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-3653\"><p>Desde el 1.\u00ba trimestre del curso 2017-2018, a las recepciones de Pineda y Avantis hay contenedores de recogida de pilas usadas. Estamos muy contentas porque ha tenido una muy buena recibimiento. Sigamos as\u00ed!<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2384\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.10.23-300x264.png\" alt=\"\" width=\"300\" height=\"264\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.10.23-300x264.png 300w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.10.23-1024x902.png 1024w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.10.23-768x676.png 768w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.10.23-1536x1353.png 1536w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.10.23-2048x1804.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3654\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-3654\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ya tenemos parking de bicicletas!<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3654\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-3654\"><p>Desde el d\u00eda 8 de enero en la entrada de Pineda ya tenemos un parking por bicicletas. Recordamos que cuando vayamos en bicicleta estamos haciendo ejercicio saludable y nos ahorramos emisiones de CO\u2082 y contaminar el aire de nuestra ciudad.<br \/>Os animamos a todas a usarlo!<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2383\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.08.21-300x195.png\" alt=\"\" width=\"300\" height=\"195\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.08.21-300x195.png 300w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.08.21-1024x667.png 1024w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.08.21-768x500.png 768w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.08.21-1536x1001.png 1536w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.08.21-2048x1334.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3655\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-3655\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Campa\u00f1a de reciclaje y reutilizaci\u00f3n de papeles en las aulas de Pineda<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3655\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-3655\"><p>Este curso hemos continuado con el reciclaje de papel en todas las aulas de Pineda, tan de primaria como de secundaria. Las alumnas tienen muy integrado donde tienen que tirar el papel y vac\u00edan las papeleras una vez a la semana.<br \/>Tambi\u00e9n hemos colocado bandejas de \u00abhojas en bruto\u00bb para hacer ejercicios, borradores&#8230; Estamos muy contentas porque ha funcionado muy bien!<br \/>Felicidades chicas! Lo estamos haciendo muy bien!<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2385\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.12.10-300x213.png\" alt=\"\" width=\"300\" height=\"213\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.12.10-300x213.png 300w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.12.10-1024x727.png 1024w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.12.10-768x545.png 768w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.12.10-1536x1091.png 1536w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/09\/Captura-de-pantalla-2021-09-28-a-las-17.12.10-2048x1454.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3656\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-3656\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Voluntariado Verde en Secundaria<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3656\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-3656\"><p>Las alumnas de secundaria hacen acciones de Voluntariado Verd dentro de la jornada de voluntariado que organiza la Escuela Solidaria.<\/p><p>Las alumnas de 4.\u00ba de la ESO estuvieron localizando nidos de vencejos a las paredes y fachadas de los edificios del barrio de Sta. Eul\u00e0lia de L&#8217;H con la ayuda de la t\u00e9cnica del Ayuntamiento de L&#8217;H Merc\u00e8 Alc\u00e1zar.<\/p><p>Un grupo de 1.\u00ba de bachillerato fueron al pinar del Array\u00e1n (Gav\u00e0), que forma parte del Parque Natural del Delta del Llobregat. All\u00e1, con la ayuda del t\u00e9cnico N\u00e8stor Urios, estuvieron localizando y arrancando la plantas invasoras y tambi\u00e9n limpiando el pinar de desechos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3657\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-3657\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Taller de reciclaje de papel para las Puertas Abiertas<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3657\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-3657\"><p>Las alumnas de 1.\u00ba de ESO han preparado un taller con material de papel reciclado para todos los ni\u00f1os y ni\u00f1as que vengan a la Jornada de Puertas Abiertas 2017.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3658\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-3658\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Participaci\u00f3n al IV Foro XESC del Baix Llobregat<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3658\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-3658\"><p>Las alumnas de Primaria Blanca Gonz\u00e1lez, Abril Lambea, Anna Fabregat i S\u00edlvia Rodr\u00edguez participaron en el IV Foro XESC Baix Llobregat, una jornada de intercambio de experiencias entre escuelas donde se reflexionaba sobre la prevenci\u00f3n y el reaprovechamiento de los residuos, para conseguir un mundo m\u00e1s sostenible.<\/p><p>Las alumnas prepararon una infograf\u00eda donde se resum\u00edan las accionas que Pineda est\u00e1 llevando a cabo a propuesta de nuestra escuela verde. Tambi\u00e9n hubo un mercado de intercambio donde cada alumna entregaba un objeto o una acci\u00f3n con el fin de dar una segunda vida a las cosas.<\/p><p>Acompa\u00f1amos la noticia del testigo de cada una de las participantes:<\/p><p>Blanca Gonz\u00e1lez: \u201cMe ha gustado much\u00edsimo esta experiencia porque creo que me ha servido como motivaci\u00f3n personal para reciclar y me ha parecido genial que cada escuela hiciera propuesta de mejora.\u201d<\/p><p>Anna Fabregat: \u201cEl mejor ha estado disfrutar con mis compa\u00f1eras y el mercado de intercambio donde nos d\u00e1bamos los objetos que no utilizamos\u201d.<\/p><p>Abril Lambea: \u201cMe ha encanta ir al foro XESC y poder intercambiar experiencias. Nos han hecho un taller de reciclaje de libretas, ha sido un pase!\u201d<\/p><p>Silvia Rodr\u00edguez \u201cMi experiencia ha sido \u00fanica, he aprendido ideas por el colegio y por el d\u00eda a d\u00eda.\u201d<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dea77c elementor-widget elementor-widget-spacer\" data-id=\"2dea77c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b92576 elementor-widget elementor-widget-heading\" data-id=\"9b92576\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Consultas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c57002 elementor-widget elementor-widget-text-editor\" data-id=\"5c57002\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Puede ponerse en contacto con nosotros para comentar cualquier duda, sugerencia o consulta a trav\u00e9s del correo <a href=\"mailto:escolaverda@pineda.es\">escolaverda@pineda.es<\/a><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-851ce18 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"851ce18\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c40f024\" data-id=\"c40f024\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-1095be2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1095be2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dda6958\" data-id=\"dda6958\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b51ae8 elementor-widget elementor-widget-image\" data-id=\"8b51ae8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avantis.edu.es\/es\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"97\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Avantis_logo-300x97.png\" class=\"attachment-medium size-medium wp-image-3174\" alt=\"\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Avantis_logo-300x97.png 300w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Avantis_logo-1024x333.png 1024w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Avantis_logo-768x250.png 768w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Avantis_logo-1536x499.png 1536w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Avantis_logo.png 1945w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ca342b3\" data-id=\"ca342b3\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba0c35f elementor-widget elementor-widget-image\" data-id=\"ba0c35f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pineda.es\/es\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-1LOGO-PINEDA-300x111.png\" class=\"attachment-medium size-medium wp-image-3105\" alt=\"\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-1LOGO-PINEDA-300x111.png 300w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-1LOGO-PINEDA.png 735w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3dc3749\" data-id=\"3dc3749\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64e74fc elementor-widget elementor-widget-image\" data-id=\"64e74fc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.xaloc.org\/es\/index.htm\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"90\" src=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-1LOGO-XALOC-300x90.png\" class=\"attachment-medium size-medium wp-image-3140\" alt=\"\" srcset=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-1LOGO-XALOC-300x90.png 300w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-1LOGO-XALOC-1024x309.png 1024w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-1LOGO-XALOC-768x232.png 768w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-1LOGO-XALOC-1536x463.png 1536w, https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-1LOGO-XALOC-2048x618.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-91f39f9 elementor-widget elementor-widget-spacer\" data-id=\"91f39f9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ESCUELA VERDE Aprender a vivir de manera sostenible. Buscar alternativas y soluciones pr\u00e1cticas para tener cuidado del planeta. Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3164,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-3687","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a (XESC).\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/pineda.es\/es\/escuela-verde\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Pineda - Inspirant el futur\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Escuela verde - Pineda\" \/>\n\t\t<meta property=\"og:description\" content=\"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a (XESC).\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/pineda.es\/es\/escuela-verde\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1513\" \/>\n\t\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-11-17T12:43:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-12-12T12:26:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Escuela verde - Pineda\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a (XESC).\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/escuela-verde\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pineda.es\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/escuela-verde\\\/#listItem\",\"name\":\"Escuela verde\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/escuela-verde\\\/#listItem\",\"position\":2,\"name\":\"Escuela verde\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#organization\",\"name\":\"Pineda\",\"description\":\"Inspirant el futur\",\"url\":\"https:\\\/\\\/pineda.es\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/pineda.es\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Recurso-2pago-seguro.png\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/escuela-verde\\\/#organizationLogo\",\"width\":1513,\"height\":556},\"image\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/escuela-verde\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/pineda_edu\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/escuela-verde\\\/#webpage\",\"url\":\"https:\\\/\\\/pineda.es\\\/es\\\/escuela-verde\\\/\",\"name\":\"Escuela verde - Pineda\",\"description\":\"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\\u00f1a (XESC).\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/escuela-verde\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/pineda.es\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/avantpmm-2167-scaled.jpg\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/escuela-verde\\\/#mainImage\",\"width\":2560,\"height\":1703},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/escuela-verde\\\/#mainImage\"},\"datePublished\":\"2021-11-17T13:43:23+01:00\",\"dateModified\":\"2024-12-12T13:26:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/pineda.es\\\/es\\\/\",\"name\":\"Pineda\",\"description\":\"Inspirant el futur\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Escuela verde - Pineda","description":"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a (XESC).","canonical_url":"https:\/\/pineda.es\/es\/escuela-verde\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/pineda.es\/es\/escuela-verde\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/pineda.es\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/pineda.es\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pineda.es\/es\/escuela-verde\/#listItem","name":"Escuela verde"}},{"@type":"ListItem","@id":"https:\/\/pineda.es\/es\/escuela-verde\/#listItem","position":2,"name":"Escuela verde","previousItem":{"@type":"ListItem","@id":"https:\/\/pineda.es\/es\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/pineda.es\/es\/#organization","name":"Pineda","description":"Inspirant el futur","url":"https:\/\/pineda.es\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png","@id":"https:\/\/pineda.es\/es\/escuela-verde\/#organizationLogo","width":1513,"height":556},"image":{"@id":"https:\/\/pineda.es\/es\/escuela-verde\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/pineda_edu\/"]},{"@type":"WebPage","@id":"https:\/\/pineda.es\/es\/escuela-verde\/#webpage","url":"https:\/\/pineda.es\/es\/escuela-verde\/","name":"Escuela verde - Pineda","description":"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a (XESC).","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/pineda.es\/es\/#website"},"breadcrumb":{"@id":"https:\/\/pineda.es\/es\/escuela-verde\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/avantpmm-2167-scaled.jpg","@id":"https:\/\/pineda.es\/es\/escuela-verde\/#mainImage","width":2560,"height":1703},"primaryImageOfPage":{"@id":"https:\/\/pineda.es\/es\/escuela-verde\/#mainImage"},"datePublished":"2021-11-17T13:43:23+01:00","dateModified":"2024-12-12T13:26:36+01:00"},{"@type":"WebSite","@id":"https:\/\/pineda.es\/es\/#website","url":"https:\/\/pineda.es\/es\/","name":"Pineda","description":"Inspirant el futur","inLanguage":"es-ES","publisher":{"@id":"https:\/\/pineda.es\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Pineda - Inspirant el futur","og:type":"article","og:title":"Escuela verde - Pineda","og:description":"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a (XESC).","og:url":"https:\/\/pineda.es\/es\/escuela-verde\/","og:image":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png","og:image:secure_url":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png","og:image:width":1513,"og:image:height":556,"article:published_time":"2021-11-17T12:43:23+00:00","article:modified_time":"2024-12-12T12:26:36+00:00","twitter:card":"summary","twitter:title":"Escuela verde - Pineda","twitter:description":"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a (XESC).","twitter:image":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png"},"aioseo_meta_data":{"post_id":"3687","title":null,"description":"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a (XESC).","keywords":null,"keyphrases":{"focus":{"keyphrase":"escuela verde","score":82,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-07-15 18:35:48","updated":"2025-06-05 08:11:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/pineda.es\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEscuela verde\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/pineda.es\/es\/"},{"label":"Escuela verde","link":"https:\/\/pineda.es\/es\/escuela-verde\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Escuela verde - Pineda<\/title>\n<meta name=\"description\" content=\"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pineda.es\/es\/escuela-verde\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escuela verde - Pineda\" \/>\n<meta property=\"og:description\" content=\"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pineda.es\/es\/escuela-verde\/\" \/>\n<meta property=\"og:site_name\" content=\"Pineda\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-12T12:26:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/avantpmm-2167-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pineda.es\/es\/escuela-verde\/\",\"url\":\"https:\/\/pineda.es\/es\/escuela-verde\/\",\"name\":\"Escuela verde - Pineda\",\"isPartOf\":{\"@id\":\"https:\/\/pineda.es\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pineda.es\/es\/escuela-verde\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pineda.es\/es\/escuela-verde\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/avantpmm-2167-scaled.jpg\",\"datePublished\":\"2021-11-17T12:43:23+00:00\",\"dateModified\":\"2024-12-12T12:26:36+00:00\",\"description\":\"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a.\",\"breadcrumb\":{\"@id\":\"https:\/\/pineda.es\/es\/escuela-verde\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pineda.es\/es\/escuela-verde\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pineda.es\/es\/escuela-verde\/#primaryimage\",\"url\":\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/avantpmm-2167-scaled.jpg\",\"contentUrl\":\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/avantpmm-2167-scaled.jpg\",\"width\":2560,\"height\":1703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pineda.es\/es\/escuela-verde\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pineda.es\/es\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escuela verde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pineda.es\/es\/#website\",\"url\":\"https:\/\/pineda.es\/es\/\",\"name\":\"Pineda\",\"description\":\"Inspirant el futur\",\"publisher\":{\"@id\":\"https:\/\/pineda.es\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pineda.es\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pineda.es\/es\/#organization\",\"name\":\"Pineda\",\"url\":\"https:\/\/pineda.es\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pineda.es\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png\",\"contentUrl\":\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png\",\"width\":1513,\"height\":556,\"caption\":\"Pineda\"},\"image\":{\"@id\":\"https:\/\/pineda.es\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escuela verde - Pineda","description":"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pineda.es\/es\/escuela-verde\/","og_locale":"es_ES","og_type":"article","og_title":"Escuela verde - Pineda","og_description":"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a.","og_url":"https:\/\/pineda.es\/es\/escuela-verde\/","og_site_name":"Pineda","article_modified_time":"2024-12-12T12:26:36+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/avantpmm-2167-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pineda.es\/es\/escuela-verde\/","url":"https:\/\/pineda.es\/es\/escuela-verde\/","name":"Escuela verde - Pineda","isPartOf":{"@id":"https:\/\/pineda.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pineda.es\/es\/escuela-verde\/#primaryimage"},"image":{"@id":"https:\/\/pineda.es\/es\/escuela-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/avantpmm-2167-scaled.jpg","datePublished":"2021-11-17T12:43:23+00:00","dateModified":"2024-12-12T12:26:36+00:00","description":"Pineda es una escuela verde, comprometida con el medio ambiente. Formamos parte de la Red de Escuelas por la Sostenibilidad de Catalu\u00f1a.","breadcrumb":{"@id":"https:\/\/pineda.es\/es\/escuela-verde\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pineda.es\/es\/escuela-verde\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pineda.es\/es\/escuela-verde\/#primaryimage","url":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/avantpmm-2167-scaled.jpg","contentUrl":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/avantpmm-2167-scaled.jpg","width":2560,"height":1703},{"@type":"BreadcrumbList","@id":"https:\/\/pineda.es\/es\/escuela-verde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pineda.es\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Escuela verde"}]},{"@type":"WebSite","@id":"https:\/\/pineda.es\/es\/#website","url":"https:\/\/pineda.es\/es\/","name":"Pineda","description":"Inspirant el futur","publisher":{"@id":"https:\/\/pineda.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pineda.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pineda.es\/es\/#organization","name":"Pineda","url":"https:\/\/pineda.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pineda.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png","contentUrl":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png","width":1513,"height":556,"caption":"Pineda"},"image":{"@id":"https:\/\/pineda.es\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/pages\/3687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/comments?post=3687"}],"version-history":[{"count":72,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/pages\/3687\/revisions"}],"predecessor-version":[{"id":23241,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/pages\/3687\/revisions\/23241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/media\/3164"}],"wp:attachment":[{"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/media?parent=3687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}