{"id":15580,"date":"2023-02-27T13:37:18","date_gmt":"2023-02-27T12:37:18","guid":{"rendered":"https:\/\/pineda.es\/dates-de-les-preinscripcions-del-curs-23-24\/"},"modified":"2023-02-27T14:01:55","modified_gmt":"2023-02-27T13:01:55","slug":"dates-de-les-preinscripcions-del-curs-23-24","status":"publish","type":"post","link":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/","title":{"rendered":"Fechas de las preinscripciones del Curso 23-24"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"15580\" class=\"elementor elementor-15580 elementor-15567\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-76a30ad5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76a30ad5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f446c03\" data-id=\"6f446c03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16a92db elementor-widget elementor-widget-heading\" data-id=\"16a92db\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb21af9 elementor-widget elementor-widget-heading\" data-id=\"cb21af9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Recomendamos formalizar la preinscripci\u00f3n los tres primeros d\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar alg\u00fan dato<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40bd6c9 elementor-widget elementor-widget-text-editor\" data-id=\"40bd6c9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ya est\u00e1n publicadas las fechas de las <strong>Preinscripciones del Curso 23-24<\/strong>:<\/p>\n<ul>\n<li><strong>Primaria<\/strong>: del 6 al 20 de marzo.<\/li>\n<li><strong>Secundaria:<\/strong> del 8 al 20 de marzo.<\/li>\n<li><strong>Bachillerato<\/strong>: del 20 al 26 de abril<\/li>\n<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f85a7f7 elementor-widget elementor-widget-text-editor\" data-id=\"f85a7f7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Recordad que recomendamos formalizar la preinscripci\u00f3n los tres primeros d\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar alg\u00fan dato.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae47f1f elementor-widget elementor-widget-text-editor\" data-id=\"ae47f1f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Podr\u00e9is encontrar toda la informaci\u00f3n necesaria para realizar la matr\u00edcula con \u00e9xito <span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/pineda.es\/es\/preinscripcio-curs-23-24\/\">AQU\u00cd<\/a><\/strong><\/span>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99abe7e elementor-widget elementor-widget-text-editor\" data-id=\"99abe7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Si os surgiera cualquier duda, pod\u00e9is llamar a la escuela (93.263.79.90) de 9 a 14 horas y preguntar por Sofia Soriano, quien os ayudar\u00e1 a resolverlo, o enviarle un correo electr\u00f3nico a <span style=\"text-decoration: underline;\"><strong><a href=\"mailto:s.sorianol@pineda.es\" target=\"_blank\" rel=\"noopener\">s.sorianol@pineda.es<\/a><\/strong><\/span>.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1468d2a elementor-widget elementor-widget-text-editor\" data-id=\"1468d2a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"titol-seccio\">\n<div class=\"container\">\n<div class=\"row\">\n<p>Para estar actualizado a diario puede seguirnos en nuestro <a href=\"https:\/\/www.instagram.com\/pineda_edu\/?hl=es\">Instagram.<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0a1c109 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a1c109\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-270f5cd\" data-id=\"270f5cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-100f448 elementor-widget elementor-widget-text-editor\" data-id=\"100f448\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\">En Pineda enfocamos el Bachillerato como un periodo para abrir horizontes y prepararse para un futuro lleno de oportunidades y para ser agentes de cambio en la sociedad. Una carrera profesional de \u00e9xito no consta solo de una buena preparaci\u00f3n acad\u00e9mica. Es esencial conseguir un alto grado de <b>autoconocimiento<\/b> y unas <b>habilidades emocionales<\/b> y personales que permitan desarrollarse y ser l\u00edder en un entorno cambiante.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Potenciem els propis talents i consolidem la capacitat d\u2019esfor\u00e7 que permetr\u00e0 al nostre alumnat aconseguir les seves fites tant professionals com personals. En esta etapa es clave la preparaci\u00f3n acad\u00e9mica para los estudios posteriores \u2013universitarios o profesionales\u2013 y el contacto con el mundo laboral para conocer bien las diferentes salidas profesionales y poder elegir libremente.<\/span><\/p>\n<div class=\"elementor-element elementor-element-90ad9c3 elementor-widget elementor-widget-text-editor\" data-id=\"90ad9c3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p><span style=\"color: #ffffff;\">El siglo XXI nos plantea nuevos retos educativos y profesionales a los que tendr\u00e1n que hacer frente nuestras alumnas. Conocer sus talentos y hacerlas protagonistas de su aprendizaje es el mejor camino para que desarrollen las competencias personales y acad\u00e9micas y afronten los retos del futuro.<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-dca7372 elementor-widget elementor-widget-text-editor\" data-id=\"dca7372\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p><span style=\"color: #ffffff;\">L\u2019objectiu de Pineda \u00e9s que les alumnes siguin felices coneixent i desenvolupant els seus talents i descobrint el valor de la veritat que les portar\u00e0 a actuar amb llibertat i responsabilitat.<\/span><\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24 Recomendamos formalizar la preinscripci\u00f3n los tres primeros d\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activitats-escola"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24 Recomendamos formalizar la preinscripci\u00f3n los tres primeros d\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar alg\u00fan dato Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24: Primaria: del 6 al 20 de marzo. Secundaria: del 8 al 20\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Blanca Del Cacho\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Pineda - Inspirant el futur\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fechas de las preinscripciones del Curso 23-24 - Pineda\" \/>\n\t\t<meta property=\"og:description\" content=\"Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24 Recomendamos formalizar la preinscripci\u00f3n los tres primeros d\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar alg\u00fan dato Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24: Primaria: del 6 al 20 de marzo. Secundaria: del 8 al 20\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1513\" \/>\n\t\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-02-27T12:37:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-02-27T13:01:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fechas de las preinscripciones del Curso 23-24 - Pineda\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24 Recomendamos formalizar la preinscripci\u00f3n los tres primeros d\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar alg\u00fan dato Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24: Primaria: del 6 al 20 de marzo. Secundaria: del 8 al 20\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#blogposting\",\"name\":\"Fechas de las preinscripciones del Curso 23-24 - Pineda\",\"headline\":\"Fechas de las preinscripciones del Curso 23-24\",\"author\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/author\\\/b-delcacho\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/pineda.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/P1029552-scaled.jpg\",\"width\":2560,\"height\":1438,\"caption\":\"Dates de les preinscripcions del Curs 23-24\"},\"datePublished\":\"2023-02-27T13:37:18+01:00\",\"dateModified\":\"2023-02-27T14:01:55+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#webpage\"},\"articleSection\":\"Activitats de l'escola, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pineda.es\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/category\\\/activitats-escola\\\/#listItem\",\"name\":\"Activitats de l'escola\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/category\\\/activitats-escola\\\/#listItem\",\"position\":2,\"name\":\"Activitats de l'escola\",\"item\":\"https:\\\/\\\/pineda.es\\\/category\\\/activitats-escola\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#listItem\",\"name\":\"Fechas de las preinscripciones del Curso 23-24\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#listItem\",\"position\":3,\"name\":\"Fechas de las preinscripciones del Curso 23-24\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pineda.es\\\/category\\\/activitats-escola\\\/#listItem\",\"name\":\"Activitats de l'escola\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#organization\",\"name\":\"Pineda\",\"description\":\"Inspirant el futur\",\"url\":\"https:\\\/\\\/pineda.es\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/pineda.es\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Recurso-2pago-seguro.png\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#organizationLogo\",\"width\":1513,\"height\":556},\"image\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/pineda_edu\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/author\\\/b-delcacho\\\/#author\",\"url\":\"https:\\\/\\\/pineda.es\\\/es\\\/author\\\/b-delcacho\\\/\",\"name\":\"Blanca Del Cacho\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/64c438c9507d9c088d37ea2d946bc56cc55f8b6609d082d6fd0f557e69dabac1?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Blanca Del Cacho\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#webpage\",\"url\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/\",\"name\":\"Fechas de las preinscripciones del Curso 23-24 - Pineda\",\"description\":\"Ya est\\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24 Recomendamos formalizar la preinscripci\\u00f3n los tres primeros d\\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar alg\\u00fan dato Ya est\\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24: Primaria: del 6 al 20 de marzo. Secundaria: del 8 al 20\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/author\\\/b-delcacho\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/author\\\/b-delcacho\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/pineda.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/P1029552-scaled.jpg\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#mainImage\",\"width\":2560,\"height\":1438,\"caption\":\"Dates de les preinscripcions del Curs 23-24\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/dates-de-les-preinscripcions-del-curs-23-24\\\/#mainImage\"},\"datePublished\":\"2023-02-27T13:37:18+01:00\",\"dateModified\":\"2023-02-27T14:01:55+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/pineda.es\\\/es\\\/\",\"name\":\"Pineda\",\"description\":\"Inspirant el futur\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/pineda.es\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Fechas de las preinscripciones del Curso 23-24 - Pineda","description":"Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24 Recomendamos formalizar la preinscripci\u00f3n los tres primeros d\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar alg\u00fan dato Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24: Primaria: del 6 al 20 de marzo. Secundaria: del 8 al 20","canonical_url":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#blogposting","name":"Fechas de las preinscripciones del Curso 23-24 - Pineda","headline":"Fechas de las preinscripciones del Curso 23-24","author":{"@id":"https:\/\/pineda.es\/es\/author\/b-delcacho\/#author"},"publisher":{"@id":"https:\/\/pineda.es\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg","width":2560,"height":1438,"caption":"Dates de les preinscripcions del Curs 23-24"},"datePublished":"2023-02-27T13:37:18+01:00","dateModified":"2023-02-27T14:01:55+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#webpage"},"isPartOf":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#webpage"},"articleSection":"Activitats de l'escola, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/pineda.es\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/pineda.es\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pineda.es\/category\/activitats-escola\/#listItem","name":"Activitats de l'escola"}},{"@type":"ListItem","@id":"https:\/\/pineda.es\/category\/activitats-escola\/#listItem","position":2,"name":"Activitats de l'escola","item":"https:\/\/pineda.es\/category\/activitats-escola\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#listItem","name":"Fechas de las preinscripciones del Curso 23-24"},"previousItem":{"@type":"ListItem","@id":"https:\/\/pineda.es\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#listItem","position":3,"name":"Fechas de las preinscripciones del Curso 23-24","previousItem":{"@type":"ListItem","@id":"https:\/\/pineda.es\/category\/activitats-escola\/#listItem","name":"Activitats de l'escola"}}]},{"@type":"Organization","@id":"https:\/\/pineda.es\/es\/#organization","name":"Pineda","description":"Inspirant el futur","url":"https:\/\/pineda.es\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#organizationLogo","width":1513,"height":556},"image":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/pineda_edu\/"]},{"@type":"Person","@id":"https:\/\/pineda.es\/es\/author\/b-delcacho\/#author","url":"https:\/\/pineda.es\/es\/author\/b-delcacho\/","name":"Blanca Del Cacho","image":{"@type":"ImageObject","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/64c438c9507d9c088d37ea2d946bc56cc55f8b6609d082d6fd0f557e69dabac1?s=96&d=mm&r=g","width":96,"height":96,"caption":"Blanca Del Cacho"}},{"@type":"WebPage","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#webpage","url":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/","name":"Fechas de las preinscripciones del Curso 23-24 - Pineda","description":"Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24 Recomendamos formalizar la preinscripci\u00f3n los tres primeros d\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar alg\u00fan dato Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24: Primaria: del 6 al 20 de marzo. Secundaria: del 8 al 20","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/pineda.es\/es\/#website"},"breadcrumb":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#breadcrumblist"},"author":{"@id":"https:\/\/pineda.es\/es\/author\/b-delcacho\/#author"},"creator":{"@id":"https:\/\/pineda.es\/es\/author\/b-delcacho\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#mainImage","width":2560,"height":1438,"caption":"Dates de les preinscripcions del Curs 23-24"},"primaryImageOfPage":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#mainImage"},"datePublished":"2023-02-27T13:37:18+01:00","dateModified":"2023-02-27T14:01:55+01:00"},{"@type":"WebSite","@id":"https:\/\/pineda.es\/es\/#website","url":"https:\/\/pineda.es\/es\/","name":"Pineda","description":"Inspirant el futur","inLanguage":"es-ES","publisher":{"@id":"https:\/\/pineda.es\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Pineda - Inspirant el futur","og:type":"article","og:title":"Fechas de las preinscripciones del Curso 23-24 - Pineda","og:description":"Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24 Recomendamos formalizar la preinscripci\u00f3n los tres primeros d\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar alg\u00fan dato Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24: Primaria: del 6 al 20 de marzo. Secundaria: del 8 al 20","og:url":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/","og:image":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png","og:image:secure_url":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png","og:image:width":1513,"og:image:height":556,"article:published_time":"2023-02-27T12:37:18+00:00","article:modified_time":"2023-02-27T13:01:55+00:00","twitter:card":"summary","twitter:title":"Fechas de las preinscripciones del Curso 23-24 - Pineda","twitter:description":"Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24 Recomendamos formalizar la preinscripci\u00f3n los tres primeros d\u00edas para tener tiempo, si fuera necesario, de poder modificar o completar alg\u00fan dato Ya est\u00e1n publicadas las fechas de las Preinscripciones del Curso 23-24: Primaria: del 6 al 20 de marzo. Secundaria: del 8 al 20","twitter:image":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png"},"aioseo_meta_data":{"post_id":"15580","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-02-27 12:45:32","updated":"2025-06-05 08:36:56","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/pineda.es\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/pineda.es\/category\/activitats-escola\/\" title=\"Activitats de l&apos;escola\">Activitats de l'escola<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFechas de las preinscripciones del Curso 23-24\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/pineda.es\/es\/"},{"label":"Activitats de l'escola","link":"https:\/\/pineda.es\/category\/activitats-escola\/"},{"label":"Fechas de las preinscripciones del Curso 23-24","link":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fechas de las preinscripciones del Curso 23-24<\/title>\n<meta name=\"description\" content=\"\u00a1Ya tenemos las fechas de las preinscripciones de Primaria, Secundaria y Bachillerato del Curso 23-24 expuestas en la web!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fechas de las preinscripciones del Curso 23-24\" \/>\n<meta property=\"og:description\" content=\"\u00a1Ya tenemos las fechas de las preinscripciones de Primaria, Secundaria y Bachillerato del Curso 23-24 expuestas en la web!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Pineda\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-27T12:37:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-27T13:01:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blanca Del Cacho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blanca Del Cacho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/\"},\"author\":{\"name\":\"Blanca Del Cacho\",\"@id\":\"https:\/\/pineda.es\/es\/#\/schema\/person\/1034d811f32bc081471a2075103a8754\"},\"headline\":\"Fechas de las preinscripciones del Curso 23-24\",\"datePublished\":\"2023-02-27T12:37:18+00:00\",\"dateModified\":\"2023-02-27T13:01:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/\"},\"wordCount\":363,\"publisher\":{\"@id\":\"https:\/\/pineda.es\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg\",\"articleSection\":[\"Activitats de l'escola\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/\",\"url\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/\",\"name\":\"Fechas de las preinscripciones del Curso 23-24\",\"isPartOf\":{\"@id\":\"https:\/\/pineda.es\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg\",\"datePublished\":\"2023-02-27T12:37:18+00:00\",\"dateModified\":\"2023-02-27T13:01:55+00:00\",\"description\":\"\u00a1Ya tenemos las fechas de las preinscripciones de Primaria, Secundaria y Bachillerato del Curso 23-24 expuestas en la web!\",\"breadcrumb\":{\"@id\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#primaryimage\",\"url\":\"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg\",\"contentUrl\":\"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg\",\"width\":2560,\"height\":1438,\"caption\":\"Dates de les preinscripcions del Curs 23-24\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pineda.es\/es\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fechas de las preinscripciones del Curso 23-24\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pineda.es\/es\/#website\",\"url\":\"https:\/\/pineda.es\/es\/\",\"name\":\"Pineda\",\"description\":\"Inspirant el futur\",\"publisher\":{\"@id\":\"https:\/\/pineda.es\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pineda.es\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pineda.es\/es\/#organization\",\"name\":\"Pineda\",\"url\":\"https:\/\/pineda.es\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pineda.es\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png\",\"contentUrl\":\"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png\",\"width\":1513,\"height\":556,\"caption\":\"Pineda\"},\"image\":{\"@id\":\"https:\/\/pineda.es\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/pineda.es\/es\/#\/schema\/person\/1034d811f32bc081471a2075103a8754\",\"name\":\"Blanca Del Cacho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pineda.es\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/64c438c9507d9c088d37ea2d946bc56cc55f8b6609d082d6fd0f557e69dabac1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/64c438c9507d9c088d37ea2d946bc56cc55f8b6609d082d6fd0f557e69dabac1?s=96&d=mm&r=g\",\"caption\":\"Blanca Del Cacho\"},\"url\":\"https:\/\/pineda.es\/es\/author\/b-delcacho\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fechas de las preinscripciones del Curso 23-24","description":"\u00a1Ya tenemos las fechas de las preinscripciones de Primaria, Secundaria y Bachillerato del Curso 23-24 expuestas en la web!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/","og_locale":"es_ES","og_type":"article","og_title":"Fechas de las preinscripciones del Curso 23-24","og_description":"\u00a1Ya tenemos las fechas de las preinscripciones de Primaria, Secundaria y Bachillerato del Curso 23-24 expuestas en la web!","og_url":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/","og_site_name":"Pineda","article_published_time":"2023-02-27T12:37:18+00:00","article_modified_time":"2023-02-27T13:01:55+00:00","og_image":[{"width":2560,"height":1438,"url":"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg","type":"image\/jpeg"}],"author":"Blanca Del Cacho","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Blanca Del Cacho","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#article","isPartOf":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/"},"author":{"name":"Blanca Del Cacho","@id":"https:\/\/pineda.es\/es\/#\/schema\/person\/1034d811f32bc081471a2075103a8754"},"headline":"Fechas de las preinscripciones del Curso 23-24","datePublished":"2023-02-27T12:37:18+00:00","dateModified":"2023-02-27T13:01:55+00:00","mainEntityOfPage":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/"},"wordCount":363,"publisher":{"@id":"https:\/\/pineda.es\/es\/#organization"},"image":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#primaryimage"},"thumbnailUrl":"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg","articleSection":["Activitats de l'escola"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/","url":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/","name":"Fechas de las preinscripciones del Curso 23-24","isPartOf":{"@id":"https:\/\/pineda.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#primaryimage"},"image":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#primaryimage"},"thumbnailUrl":"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg","datePublished":"2023-02-27T12:37:18+00:00","dateModified":"2023-02-27T13:01:55+00:00","description":"\u00a1Ya tenemos las fechas de las preinscripciones de Primaria, Secundaria y Bachillerato del Curso 23-24 expuestas en la web!","breadcrumb":{"@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#primaryimage","url":"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg","contentUrl":"https:\/\/pineda.es\/wp-content\/uploads\/2023\/02\/P1029552-scaled.jpg","width":2560,"height":1438,"caption":"Dates de les preinscripcions del Curs 23-24"},{"@type":"BreadcrumbList","@id":"https:\/\/pineda.es\/es\/dates-de-les-preinscripcions-del-curs-23-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pineda.es\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Fechas de las preinscripciones del Curso 23-24"}]},{"@type":"WebSite","@id":"https:\/\/pineda.es\/es\/#website","url":"https:\/\/pineda.es\/es\/","name":"Pineda","description":"Inspirant el futur","publisher":{"@id":"https:\/\/pineda.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pineda.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pineda.es\/es\/#organization","name":"Pineda","url":"https:\/\/pineda.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pineda.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png","contentUrl":"https:\/\/pineda.es\/wp-content\/uploads\/2021\/07\/Recurso-2pago-seguro.png","width":1513,"height":556,"caption":"Pineda"},"image":{"@id":"https:\/\/pineda.es\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pineda.es\/es\/#\/schema\/person\/1034d811f32bc081471a2075103a8754","name":"Blanca Del Cacho","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pineda.es\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/64c438c9507d9c088d37ea2d946bc56cc55f8b6609d082d6fd0f557e69dabac1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/64c438c9507d9c088d37ea2d946bc56cc55f8b6609d082d6fd0f557e69dabac1?s=96&d=mm&r=g","caption":"Blanca Del Cacho"},"url":"https:\/\/pineda.es\/es\/author\/b-delcacho\/"}]}},"_links":{"self":[{"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/posts\/15580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/comments?post=15580"}],"version-history":[{"count":8,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/posts\/15580\/revisions"}],"predecessor-version":[{"id":15591,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/posts\/15580\/revisions\/15591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/media\/15569"}],"wp:attachment":[{"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/media?parent=15580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/categories?post=15580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pineda.es\/es\/wp-json\/wp\/v2\/tags?post=15580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}